{"id":207288,"date":"2023-07-31T20:42:10","date_gmt":"2023-07-31T19:42:10","guid":{"rendered":"https:\/\/www.jibble.io\/web-time-tracker"},"modified":"2026-05-02T08:41:02","modified_gmt":"2026-05-02T07:41:02","slug":"rejestrator-czasu-pracy-na-przegladarke","status":"publish","type":"page","link":"https:\/\/www.jibble.io\/pl\/rejestrator-czasu-pracy-na-przegladarke","title":{"rendered":"Rejestrator czasu pracy na przegl\u0105dark\u0119"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":51,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-feature-new-youtube.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-207288","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.8 (Yoast SEO v26.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Rejestrator czasu pracy na przegl\u0105dark\u0119 w 100% ZA DARMO<\/title>\n<meta name=\"description\" content=\"Mierz czas, ustalaj stawki i nie martw si\u0119 d\u0142u\u017cej o r\u0119czne wprowadzanie danych dzi\u0119ki rejestratorowi czasu pracy Jibble na przegl\u0105darki.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.jibble.io\/pl\/rejestrator-czasu-pracy-na-przegladarke\" \/>\n<meta property=\"og:locale\" content=\"pl_PL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rejestrator czasu pracy na przegl\u0105dark\u0119 w 100% ZA DARMO\" \/>\n<meta property=\"og:description\" content=\"Mierz czas, ustalaj stawki i nie martw si\u0119 d\u0142u\u017cej o r\u0119czne wprowadzanie danych dzi\u0119ki rejestratorowi czasu pracy Jibble na przegl\u0105darki.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.jibble.io\/pl\/rejestrator-czasu-pracy-na-przegladarke\" \/>\n<meta property=\"og:site_name\" content=\"Jibble\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-02T07:41:02+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Szacowany czas czytania\" \/>\n\t<meta name=\"twitter:data1\" content=\"9 minut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.jibble.io\/pl\/rejestrator-czasu-pracy-na-przegladarke\",\"url\":\"https:\/\/www.jibble.io\/pl\/rejestrator-czasu-pracy-na-przegladarke\",\"name\":\"Rejestrator czasu pracy na przegl\u0105dark\u0119 w 100% ZA DARMO\",\"isPartOf\":{\"@id\":\"https:\/\/www.jibble.io\/pl#website\"},\"datePublished\":\"2023-07-31T19:42:10+00:00\",\"dateModified\":\"2026-05-02T07:41:02+00:00\",\"description\":\"Mierz czas, ustalaj stawki i nie martw si\u0119 d\u0142u\u017cej o r\u0119czne wprowadzanie danych dzi\u0119ki rejestratorowi czasu pracy Jibble na przegl\u0105darki.\",\"inLanguage\":\"pl-PL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.jibble.io\/pl\/rejestrator-czasu-pracy-na-przegladarke\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.jibble.io\/pl#website\",\"url\":\"https:\/\/www.jibble.io\/pl\",\"name\":\"Jibble\",\"description\":\"Meet the new standard in time tracking software\",\"publisher\":{\"@id\":\"https:\/\/www.jibble.io\/pl#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.jibble.io\/pl?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pl-PL\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.jibble.io\/pl#organization\",\"name\":\"Jibble\",\"url\":\"https:\/\/www.jibble.io\/pl\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\/\/www.jibble.io\/pl#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.jibble.io\/wp-content\/uploads\/2022\/05\/Original-copy-923x1024.png\",\"contentUrl\":\"https:\/\/www.jibble.io\/wp-content\/uploads\/2022\/05\/Original-copy-923x1024.png\",\"width\":\"923\",\"height\":\"1024\",\"caption\":\"Jibble\"},\"image\":{\"@id\":\"https:\/\/www.jibble.io\/pl#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.linkedin.com\/company\/jibble\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Rejestrator czasu pracy na przegl\u0105dark\u0119 w 100% ZA DARMO","description":"Mierz czas, ustalaj stawki i nie martw si\u0119 d\u0142u\u017cej o r\u0119czne wprowadzanie danych dzi\u0119ki rejestratorowi czasu pracy Jibble na przegl\u0105darki.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.jibble.io\/pl\/rejestrator-czasu-pracy-na-przegladarke","og_locale":"pl_PL","og_type":"article","og_title":"Rejestrator czasu pracy na przegl\u0105dark\u0119 w 100% ZA DARMO","og_description":"Mierz czas, ustalaj stawki i nie martw si\u0119 d\u0142u\u017cej o r\u0119czne wprowadzanie danych dzi\u0119ki rejestratorowi czasu pracy Jibble na przegl\u0105darki.","og_url":"https:\/\/www.jibble.io\/pl\/rejestrator-czasu-pracy-na-przegladarke","og_site_name":"Jibble","article_modified_time":"2026-05-02T07:41:02+00:00","twitter_card":"summary_large_image","twitter_misc":{"Szacowany czas czytania":"9 minut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.jibble.io\/pl\/rejestrator-czasu-pracy-na-przegladarke","url":"https:\/\/www.jibble.io\/pl\/rejestrator-czasu-pracy-na-przegladarke","name":"Rejestrator czasu pracy na przegl\u0105dark\u0119 w 100% ZA DARMO","isPartOf":{"@id":"https:\/\/www.jibble.io\/pl#website"},"datePublished":"2023-07-31T19:42:10+00:00","dateModified":"2026-05-02T07:41:02+00:00","description":"Mierz czas, ustalaj stawki i nie martw si\u0119 d\u0142u\u017cej o r\u0119czne wprowadzanie danych dzi\u0119ki rejestratorowi czasu pracy Jibble na przegl\u0105darki.","inLanguage":"pl-PL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.jibble.io\/pl\/rejestrator-czasu-pracy-na-przegladarke"]}]},{"@type":"WebSite","@id":"https:\/\/www.jibble.io\/pl#website","url":"https:\/\/www.jibble.io\/pl","name":"Jibble","description":"Meet the new standard in time tracking software","publisher":{"@id":"https:\/\/www.jibble.io\/pl#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.jibble.io\/pl?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pl-PL"},{"@type":"Organization","@id":"https:\/\/www.jibble.io\/pl#organization","name":"Jibble","url":"https:\/\/www.jibble.io\/pl","logo":{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/www.jibble.io\/pl#\/schema\/logo\/image\/","url":"https:\/\/www.jibble.io\/wp-content\/uploads\/2022\/05\/Original-copy-923x1024.png","contentUrl":"https:\/\/www.jibble.io\/wp-content\/uploads\/2022\/05\/Original-copy-923x1024.png","width":"923","height":"1024","caption":"Jibble"},"image":{"@id":"https:\/\/www.jibble.io\/pl#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/jibble\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.jibble.io\/pl\/wp-json\/wp\/v2\/pages\/207288","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jibble.io\/pl\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.jibble.io\/pl\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.jibble.io\/pl\/wp-json\/wp\/v2\/users\/51"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jibble.io\/pl\/wp-json\/wp\/v2\/comments?post=207288"}],"version-history":[{"count":3,"href":"https:\/\/www.jibble.io\/pl\/wp-json\/wp\/v2\/pages\/207288\/revisions"}],"predecessor-version":[{"id":399596,"href":"https:\/\/www.jibble.io\/pl\/wp-json\/wp\/v2\/pages\/207288\/revisions\/399596"}],"wp:attachment":[{"href":"https:\/\/www.jibble.io\/pl\/wp-json\/wp\/v2\/media?parent=207288"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}