{"id":44673,"date":"2023-09-08T03:14:02","date_gmt":"2023-09-08T02:14:02","guid":{"rendered":"https:\/\/www.jibble.io\/?post_type=help&#038;p=44673"},"modified":"2026-04-12T15:20:28","modified_gmt":"2026-04-12T14:20:28","slug":"quels-sont-les-differents-types-de-rapports-pouvant-etre-exportes","status":"publish","type":"help","link":"https:\/\/www.jibble.io\/fr\/aide\/quels-sont-les-differents-types-de-rapports-pouvant-etre-exportes","title":{"rendered":"Quels sont les diff\u00e9rents types de rapports pouvant \u00eatre export\u00e9s ?"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Le <\/span><a href=\"https:\/\/jibble.io\/fr\">logiciel de suivi des temps<\/a><span style=\"font-weight: 400;\">\u00a0de Jibble vous fournit des informations pr\u00e9cieuses sur le temps et les pr\u00e9sences de votre personnel. L&rsquo;une des principales fonctionnalit\u00e9s est la possibilit\u00e9 de g\u00e9n\u00e9rer et d&rsquo;exporter diff\u00e9rents types de rapports qui peuvent vous aider \u00e0 prendre des d\u00e9cisions \u00e9clair\u00e9es, \u00e0 rationaliser les processus de paie et \u00e0 am\u00e9liorer la gestion globale des effectifs. <\/span><\/p>\n<p>La fonctionnalit\u00e9 d&rsquo;exportation est accessible aux propri\u00e9taires, aux administrateurs et aux managers des plans Premium et Ultimate. Cependant, il existe des distinctions dans les autorisations d&rsquo;exportation. Les managers peuvent exporter des donn\u00e9es exclusivement pour les membres ou les groupes qu&rsquo;ils g\u00e8rent, tandis que les propri\u00e9taires et les administrateurs ont la possibilit\u00e9 d&rsquo;exporter des donn\u00e9es pour tous les membres de l&rsquo;organisation.<\/p>\n<p>Dans ce guide, nous allons explorer les trois principaux types de rapports que vous pouvez exporter dans Jibble, ainsi que les diff\u00e9rents fichiers optionnels qui peuvent \u00eatre export\u00e9s.<\/p>\n<p><strong>Cet article couvre les points suivants<\/strong> :<\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><a href=\"#Rapports-sur les-feuilles-de-temps\"><span style=\"font-weight: 400;\">Rapports sur les feuilles de temps<\/span><\/a><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><a href=\"#Rapports-de-suivi-des-heures\"><span style=\"font-weight: 400;\">Rapports sur le temps pass\u00e9<\/span><\/a><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><a href=\"#Rapports-d'analyse-des-pr\u00e9sences\"><span style=\"font-weight: 400;\">Rapports sur les pr\u00e9sences<\/span><\/a><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><a href=\"#Fichiers-optionnels-pour-les-rapports\"><span style=\"font-weight: 400;\">Fichiers optionnels pour les rapports<\/span><\/a>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"2\"><a href=\"#Liste-des-feuilles-de-temps\"><span style=\"font-weight: 400;\">Liste des feuilles de temps<\/span><\/a><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"2\"><a href=\"#Liste-des-entr\u00e9es-de-temps\"><span style=\"font-weight: 400;\">Liste des entr\u00e9es de temps<\/span><\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<hr \/>\n<h2 id=\"Rapports-sur les-feuilles-de-temps\">Rapports sur les feuilles de temps<\/h2>\n<p>Le rapport sur les feuilles de temps offre un enregistrement complet des heures de travail de chaque membre de l&rsquo;\u00e9quipe sur une p\u00e9riode donn\u00e9e, en fournissant une ventilation des heures de paie, des heures normales, des heures suppl\u00e9mentaires class\u00e9es par type d&rsquo;heures suppl\u00e9mentaires, des heures de cong\u00e9s pay\u00e9s et des montants totaux facturables. Ce rapport est particuli\u00e8rement utile pour le traitement des salaires, le suivi des heures suppl\u00e9mentaires et la facturation pr\u00e9cise des clients.<\/p>\n<p><span style=\"font-weight: 400;\">Lorsque vous <\/span>\u00a0<a href=\"https:\/\/www.jibble.io\/fr\/aide\/exportation-des-feuilles-de-temps\">exportez des rapports de feuilles de temps<\/a>, le fichier t\u00e9l\u00e9charg\u00e9 par d\u00e9faut est le rapport de synth\u00e8se de la feuille de temps de l&rsquo;\u00e9quipe, dans lequel les d\u00e9tails des heures de travail de l&rsquo;ensemble de votre \u00e9quipe sont affich\u00e9s sur une seule feuille. Vous pouvez appliquer des filtres aux rapports pour n&rsquo;afficher que les informations pertinentes, telles que les donn\u00e9es d&rsquo;un groupe particulier, d&rsquo;un horaire sp\u00e9cifique ou d&rsquo;un membre particulier de l&rsquo;\u00e9quipe.<\/p>\n<p><span style=\"font-weight: 400;\"><img decoding=\"async\" class=\"three-quarter aligncenter wp-image-52208 size-large\" src=\"https:\/\/www.jibble.io\/wp-content\/uploads\/2023\/09\/Exporting-Timesheets-French-730x768.png\" alt=\"Exporting timesheet reports on the web app\" width=\"730\" height=\"768\" srcset=\"https:\/\/www.jibble.io\/wp-content\/uploads\/2023\/09\/Exporting-Timesheets-French-730x768.png 730w, https:\/\/www.jibble.io\/wp-content\/uploads\/2023\/09\/Exporting-Timesheets-French-285x300.png 285w, https:\/\/www.jibble.io\/wp-content\/uploads\/2023\/09\/Exporting-Timesheets-French-768x808.png 768w, https:\/\/www.jibble.io\/wp-content\/uploads\/2023\/09\/Exporting-Timesheets-French.png 877w\" sizes=\"(max-width: 730px) 100vw, 730px\" \/><\/span><\/p>\n<p>En plus des r\u00e9sum\u00e9s des feuilles de temps des \u00e9quipes, vous aurez la possibilit\u00e9 d&rsquo;inclure d&rsquo;autres fichiers facultatifs lors de l&rsquo;exportation des feuilles de temps :<\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\">\n<h5>Liste des feuilles de temps (feuilles de temps brutes)<\/h5>\n<\/li>\n<\/ul>\n<p>La liste des feuilles de temps contient g\u00e9n\u00e9ralement des informations d\u00e9taill\u00e9es sur les feuilles de temps de chaque employ\u00e9. Consultez la section Liste des feuilles de temps ci-dessous pour un aper\u00e7u plus d\u00e9taill\u00e9 de son contenu.<\/p>\n<ul>\n<li aria-level=\"1\">\n<h5>Liste des entr\u00e9es de temps (entr\u00e9es de temps brutes)<\/h5>\n<\/li>\n<\/ul>\n<p>La liste des saisies de temps contient g\u00e9n\u00e9ralement des informations d\u00e9taill\u00e9es sur les saisies de temps individuelles de chaque employ\u00e9. Reportez-vous \u00e0 la section Liste des entr\u00e9es de temps ci-dessous pour une description d\u00e9taill\u00e9e de son contenu.<\/p>\n<ul>\n<li aria-level=\"1\">\n<h5>Feuilles de temps par membre dans des onglets individuels<\/h5>\n<\/li>\n<\/ul>\n<p>Cette option n&rsquo;est disponible qu&rsquo;au format XLS, o\u00f9 vous recevrez les r\u00e9sum\u00e9s des feuilles de temps de l&rsquo;\u00e9quipe dans un onglet ou une feuille, ainsi que les r\u00e9sum\u00e9s des feuilles de temps individuelles de chaque membre de l&rsquo;\u00e9quipe, pr\u00e9sent\u00e9s dans des onglets ou des feuilles distincts. Cette disposition permet d&rsquo;obtenir une vue claire et organis\u00e9e des heures de travail de chaque membre et des donn\u00e9es connexes.<\/p>\n<p>Les donn\u00e9es affich\u00e9es sont similaires au r\u00e9sum\u00e9 des feuilles de temps de l&rsquo;\u00e9quipe et comprennent des d\u00e9tails tels que les heures de paie, les heures normales, les heures suppl\u00e9mentaires class\u00e9es par type d&rsquo;heures suppl\u00e9mentaires et les heures de cong\u00e9s pay\u00e9s.<\/p>\n<p><em><strong>Remarque :<\/strong> les montants totaux facturables ne sont pas affich\u00e9s pour les r\u00e9sum\u00e9s des feuilles de temps individuelles.<\/em><\/p>\n<hr \/>\n<h2 id=\"Rapports-de-suivi-des-heures\">Rapports de suivi des heures<\/h2>\n<p>Le rapport de suivi des heures fournit une vue d&rsquo;ensemble du temps consacr\u00e9 \u00e0 diverses activit\u00e9s, projets et clients, avec une ventilation des heures suivies et des montants totaux facturables. Ce rapport constitue un r\u00e9sum\u00e9 organis\u00e9 de la mani\u00e8re dont le temps est r\u00e9parti et utilis\u00e9, facilitant l&rsquo;analyse de la productivit\u00e9, la gestion des projets, la facturation des clients et l&rsquo;affectation des ressources.<\/p>\n<p><span style=\"font-weight: 400;\">Lorsque vous <\/span><a href=\"https:\/\/www.jibble.io\/fr\/aide\/exportation-des-rapports-de-temps-suivis\"><span style=\"font-weight: 400;\">exportez des rapports de suivi des heures<\/span><\/a><span style=\"font-weight: 400;\">, le fichier t\u00e9l\u00e9charg\u00e9 par d\u00e9faut est le rapport de synth\u00e8se du suivi des heures de l&rsquo;\u00e9quipe, qui affiche une ventilation des heures suivies par l&rsquo;ensemble de votre \u00e9quipe sur une seule feuille. Vous avez la possibilit\u00e9 de s\u00e9lectionner un groupe sp\u00e9cifique et un type de sous-groupe pour organiser les donn\u00e9es et mieux comprendre les relations entre les diff\u00e9rents composants.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Par exemple, si vous souhaitez examiner les sp\u00e9cificit\u00e9s de toutes les activit\u00e9s class\u00e9es par membres individuels, vous pouvez regrouper les donn\u00e9es par activit\u00e9s, puis les sous-grouper en fonction des membres.<br \/>\n<img decoding=\"async\" class=\"three-quarter aligncenter wp-image-52214 size-large\" src=\"https:\/\/www.jibble.io\/wp-content\/uploads\/2023\/09\/Exporting-Tracked-Time-Reports-French-733x768.png\" alt=\"Exporting tracked time reports on the web app\" width=\"733\" height=\"768\" srcset=\"https:\/\/www.jibble.io\/wp-content\/uploads\/2023\/09\/Exporting-Tracked-Time-Reports-French-733x768.png 733w, https:\/\/www.jibble.io\/wp-content\/uploads\/2023\/09\/Exporting-Tracked-Time-Reports-French-286x300.png 286w, https:\/\/www.jibble.io\/wp-content\/uploads\/2023\/09\/Exporting-Tracked-Time-Reports-French-768x805.png 768w, https:\/\/www.jibble.io\/wp-content\/uploads\/2023\/09\/Exporting-Tracked-Time-Reports-French.png 881w\" sizes=\"(max-width: 733px) 100vw, 733px\" \/><\/span><\/p>\n<p><span style=\"font-weight: 400;\">En outre, vous pouvez appliquer des filtres aux rapports afin de n&rsquo;afficher que les informations les plus importantes, telles que les donn\u00e9es d&rsquo;un groupe particulier, d&rsquo;une activit\u00e9 sp\u00e9cifique ou d&rsquo;un client particulier. Lors de l&rsquo;exportation des rapports de suivi des temps, vous pouvez choisir d&rsquo;inclure des fichiers suppl\u00e9mentaires, notamment :<\/span><\/p>\n<ul>\n<li>\n<h5>Liste des entr\u00e9es de temps (entr\u00e9es de temps brutes)<\/h5>\n<\/li>\n<\/ul>\n<p>La liste des entr\u00e9es de temps comprend g\u00e9n\u00e9ralement des informations d\u00e9taill\u00e9es sur les entr\u00e9es de temps individuelles de chaque employ\u00e9. Reportez-vous \u00e0 la section Liste des entr\u00e9es de temps ci-dessous pour une description d\u00e9taill\u00e9e de son contenu.<\/p>\n<hr \/>\n<h2 id=\"Rapports-d'analyse-des-pr\u00e9sences\">Rapports d&rsquo;analyse des pr\u00e9sences<\/h2>\n<p>Le rapport Aper\u00e7u des pr\u00e9sences fournit des informations sur les sch\u00e9mas de pr\u00e9sence des employ\u00e9s, offrant aux responsables des ressources humaines et aux superviseurs les moyens de superviser les tendances en mati\u00e8re de pr\u00e9sence. Ces informations comprennent des comparaisons entre les jours de travail pr\u00e9vus et les jours de travail r\u00e9els, des enregistrements d&rsquo;absent\u00e9isme, des cas d&rsquo;arriv\u00e9e tardive et de d\u00e9part anticip\u00e9, des pauses d\u00e9pass\u00e9es et le temps cumul\u00e9 perdu en raison de ces facteurs.<\/p>\n<p><span style=\"font-weight: 400;\">Lors de l&rsquo;<\/span><a href=\"https:\/\/www.jibble.io\/help\/timesheets-reports\/exporting-attendance-reports\"><span style=\"font-weight: 400;\">exportation de rapports sur l&rsquo;aper\u00e7u des pr\u00e9sences<\/span><\/a><span style=\"font-weight: 400;\">, le fichier t\u00e9l\u00e9charg\u00e9 par d\u00e9faut est le rapport r\u00e9capitulatif des pr\u00e9sences de l&rsquo;\u00e9quipe, dans lequel les d\u00e9tails des heures de travail de l&rsquo;ensemble de votre \u00e9quipe et les donn\u00e9es relatives aux pr\u00e9sences sont affich\u00e9s sur une seule feuille. Si vous avez plusieurs types de plannings de travail, les r\u00e9sum\u00e9s de pr\u00e9sence seront class\u00e9s en plannings fixes et flexibles.<img decoding=\"async\" class=\"three-quarter aligncenter wp-image-52219 size-large\" src=\"https:\/\/www.jibble.io\/wp-content\/uploads\/2023\/09\/Exporting-Attendance-Report-French-731x768.png\" alt=\"Exporting attendance insights reports on the web app\" width=\"731\" height=\"768\" srcset=\"https:\/\/www.jibble.io\/wp-content\/uploads\/2023\/09\/Exporting-Attendance-Report-French-731x768.png 731w, https:\/\/www.jibble.io\/wp-content\/uploads\/2023\/09\/Exporting-Attendance-Report-French-286x300.png 286w, https:\/\/www.jibble.io\/wp-content\/uploads\/2023\/09\/Exporting-Attendance-Report-French-768x807.png 768w, https:\/\/www.jibble.io\/wp-content\/uploads\/2023\/09\/Exporting-Attendance-Report-French.png 869w\" sizes=\"(max-width: 731px) 100vw, 731px\" \/><\/span><\/p>\n<p><span style=\"font-weight: 400;\">De plus, vous pouvez appliquer des filtres au rapport pour n&rsquo;afficher que des donn\u00e9es sp\u00e9cifiques, telles que les sch\u00e9mas de pr\u00e9sence d&rsquo;un groupe particulier, d&rsquo;un type de planning distinct ou d&rsquo;un membre individuel de l&rsquo;\u00e9quipe. Lors de l&rsquo;exportation des rapports de pr\u00e9sence, vous pouvez choisir d&rsquo;inclure d&rsquo;autres fichiers facultatifs, notamment :<\/span><b><\/b><\/p>\n<ul>\n<li aria-level=\"1\">\n<h5>R\u00e9sum\u00e9 des pr\u00e9sences par membre dans des onglets individuels<\/h5>\n<\/li>\n<\/ul>\n<p>Si cette option est s\u00e9lectionn\u00e9e, vous recevrez les r\u00e9sum\u00e9s des pr\u00e9sences de l&rsquo;\u00e9quipe dans un onglet ou une feuille, ainsi que les r\u00e9sum\u00e9s des pr\u00e9sences de chaque membre de l&rsquo;\u00e9quipe, pr\u00e9sent\u00e9s dans des onglets ou des feuilles distincts.<\/p>\n<p>Les donn\u00e9es affich\u00e9es sont similaires \u00e0 celles du r\u00e9capitulatif de pr\u00e9sence de l&rsquo;\u00e9quipe, y compris des d\u00e9tails tels que l&rsquo;absent\u00e9isme, les arriv\u00e9es tardives, les d\u00e9parts anticip\u00e9s, les pauses d\u00e9pass\u00e9es et le temps perdu cumul\u00e9.<\/p>\n<p><em><strong>Remarque :<\/strong> les comparaisons entre les jours de travail pr\u00e9vus et les jours de travail r\u00e9els ne sont pas affich\u00e9es pour les r\u00e9capitulatifs de pr\u00e9sence individuels.<\/em><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\">\n<h5>Liste des feuilles de temps (feuilles de temps brutes)<\/h5>\n<\/li>\n<\/ul>\n<p>La liste des feuilles de temps comprend g\u00e9n\u00e9ralement des informations d\u00e9taill\u00e9es contenues dans les feuilles de temps de chaque employ\u00e9. Consultez la section Liste des feuilles de temps ci-dessous pour un aper\u00e7u complet de son contenu.<br \/>\n<b><\/b><\/p>\n<ul>\n<li aria-level=\"1\">\n<h5>Liste des entr\u00e9es de temps (entr\u00e9es de temps brutes)<\/h5>\n<\/li>\n<\/ul>\n<p>La liste des saisies de temps comprend g\u00e9n\u00e9ralement des informations d\u00e9taill\u00e9es sur les saisies de temps individuelles de chaque employ\u00e9. Reportez-vous \u00e0 la section Liste des entr\u00e9es de temps ci-dessous pour une analyse plus d\u00e9taill\u00e9e de son contenu.<\/p>\n<hr \/>\n<h2 id=\"Fichiers-optionnels-pour-les-rapports\">Fichiers optionnels pour les rapports<\/h2>\n<p>Selon le type de rapport, vous pouvez s\u00e9lectionner des fichiers optionnels ou suppl\u00e9mentaires \u00e0 inclure lors de la cr\u00e9ation de rapports. Ces fichiers suppl\u00e9mentaires peuvent fournir un contexte ou des d\u00e9tails suppl\u00e9mentaires afin d&rsquo;am\u00e9liorer les informations contenues dans les rapports. Les deux types de fichiers optionnels les plus courants sont les suivants :<\/p>\n<ul>\n<li>\n<h5 id=\"Liste-des-feuilles-de-temps\">Liste des feuilles de temps (feuilles de temps brutes)<\/h5>\n<\/li>\n<\/ul>\n<p>La liste des feuilles de temps contient g\u00e9n\u00e9ralement des informations d\u00e9taill\u00e9es sur les feuilles de temps de chaque employ\u00e9. Voici les d\u00e9tails les plus courants :<\/p>\n<ol>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><strong>Date &amp; Jour :<\/strong> La date et le jour sp\u00e9cifiques pour lesquels les heures sont enregistr\u00e9es.<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><strong>Nom complet et code de membre :<\/strong> Le nom de l&#8217;employ\u00e9 dont les heures sont enregistr\u00e9es, ainsi que le code d&rsquo;identification de l&#8217;employ\u00e9.<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><strong>Groupe :<\/strong> Le groupe auquel l&#8217;employ\u00e9 est affect\u00e9.<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><strong>Manager(s) :<\/strong> Le nom des managers affect\u00e9s \u00e0 l&#8217;employ\u00e9.<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><strong>Heures suivies :<\/strong> Le nombre total d&rsquo;heures suivies par l&#8217;employ\u00e9, y compris les pauses.<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><strong>Heures travaill\u00e9es :<\/strong> Le nombre total d&rsquo;heures travaill\u00e9es par l&#8217;employ\u00e9, \u00e0 l&rsquo;exclusion des pauses.<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><strong>Heures de pause :<\/strong> La dur\u00e9e totale des pauses prises par l&#8217;employ\u00e9, class\u00e9e en pauses pay\u00e9es et non pay\u00e9es.<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><strong>D\u00e9ductions :<\/strong> Le nombre total d&rsquo;heures de d\u00e9ductions automatiques appliqu\u00e9es, calcul\u00e9es sur la base du seuil d\u00e9fini.<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><strong>Heures de paie :<\/strong> Le nombre total d&rsquo;heures travaill\u00e9es par l&#8217;employ\u00e9, y compris les heures normales, les heures suppl\u00e9mentaires et les cong\u00e9s pay\u00e9s. Les heures de paie servent de base au calcul de la r\u00e9mun\u00e9ration totale d&rsquo;un salari\u00e9.<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><strong>Heures normales :<\/strong> Le nombre total d&rsquo;heures travaill\u00e9es par le salari\u00e9, \u00e0 l&rsquo;exclusion des heures suppl\u00e9mentaires.<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><strong>Heures suppl\u00e9mentaires :<\/strong> Le nombre total d&rsquo;heures travaill\u00e9es au-del\u00e0 des heures de travail normales, calcul\u00e9 sur la base du seuil d\u00e9fini et class\u00e9 par type d&rsquo;heures suppl\u00e9mentaires.<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><strong>Taux d&rsquo;heures suppl\u00e9mentaires :<\/strong> Les taux appliqu\u00e9s \u00e0 chaque type d&rsquo;heures suppl\u00e9mentaires, calcul\u00e9s sur la base de la valeur multiplicatrice d\u00e9finie.<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><strong>Cong\u00e9 pay\u00e9 :<\/strong> le nombre total d&rsquo;heures pendant lesquelles l&#8217;employ\u00e9 est r\u00e9mun\u00e9r\u00e9 pour un cong\u00e9 pay\u00e9.<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><strong>Taux facturable :<\/strong> Le taux horaire appliqu\u00e9 aux heures de travail d&rsquo;un employ\u00e9, calcul\u00e9 sur la base du taux facturable d\u00e9fini.<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><strong>Montant facturable :<\/strong> La somme de toutes les heures facturables effectu\u00e9es par l&#8217;employ\u00e9, multipli\u00e9e par le taux facturable pour ces heures.<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><strong>Premi\u00e8re entr\u00e9e et derni\u00e8re sortie :<\/strong> Les heures exactes auxquelles l&#8217;employ\u00e9 a point\u00e9 au d\u00e9but de la journ\u00e9e (premi\u00e8re entr\u00e9e) et \u00e0 la fin de la journ\u00e9e (derni\u00e8re sortie).<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><strong>D\u00e9but et fin de la pause :<\/strong> Les heures exactes auxquelles l&#8217;employ\u00e9 a commenc\u00e9 sa (ses) pause(s) (d\u00e9but de la pause) et a termin\u00e9 sa (ses) pause(s) (fin de la pause), class\u00e9es par type de pause.<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<ul>\n<li id=\"Liste-des-entr\u00e9es-de-temps\">\n<h5>Liste des entr\u00e9es de temps (entr\u00e9es de temps brutes)<\/h5>\n<\/li>\n<\/ul>\n<p>La liste des entr\u00e9es de temps comprend g\u00e9n\u00e9ralement des informations d\u00e9taill\u00e9es sur les entr\u00e9es de temps individuelles de chaque employ\u00e9. Voici les d\u00e9tails les plus courants :<\/p>\n<ol>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><strong>Date :<\/strong> La date sp\u00e9cifique pour laquelle les heures sont enregistr\u00e9es.<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><strong>Nom complet et code de membre :<\/strong> Le nom de l&#8217;employ\u00e9 dont les heures sont enregistr\u00e9es, ainsi que son code d&rsquo;identification.<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><strong>Responsable(s) et code(s) de responsable(s) :<\/strong> Les noms des managers assign\u00e9s \u00e0 l&#8217;employ\u00e9, ainsi que le code d&rsquo;identification de l&#8217;employ\u00e9.<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><strong>Type d&rsquo;entr\u00e9e :<\/strong> La nature de l&rsquo;entr\u00e9e de temps, comme le pointage, la sortie et la pause.<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><strong>Heure et dur\u00e9e<\/strong> : L&rsquo;heure exacte \u00e0 laquelle la saisie a \u00e9t\u00e9 effectu\u00e9e, ainsi que la dur\u00e9e associ\u00e9e \u00e0 la saisie.<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><strong>Pause et type de pause :<\/strong> Le nom de la pause prise et le type de pause, par exemple une pause pay\u00e9e ou non pay\u00e9e.<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><strong>Projet et code de projet :<\/strong> Le projet sp\u00e9cifique et le code du projet associ\u00e9s \u00e0 la saisie de temps.<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><strong>Lieu du projet :<\/strong> Le nom de la localisation assign\u00e9e au projet.<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><strong>Activit\u00e9 et code d&rsquo;activit\u00e9 :<\/strong> L&rsquo;activit\u00e9 sp\u00e9cifique et le code d&rsquo;activit\u00e9 associ\u00e9s \u00e0 la saisie de temps.<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><strong>Client et code client :<\/strong> Le client sp\u00e9cifique et le code client associ\u00e9s \u00e0 la saisie de temps.<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><strong>Montant facturable :<\/strong> La somme de toutes les heures facturables associ\u00e9es \u00e0 la saisie de temps, multipli\u00e9e par le taux facturable pour ces heures.<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><strong>Notes :<\/strong> Commentaires ou notes suppl\u00e9mentaires ajout\u00e9s \u00e0 la saisie des temps.<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><strong>Dispositif d&rsquo;enregistrement de pointage et nom du dispositif :<\/strong> Le type d&rsquo;appareil utilis\u00e9 par l&#8217;employ\u00e9, ainsi que le nom ou l&rsquo;identifiant de l&rsquo;appareil.<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><strong>Lieu et adresse du pointage :<\/strong> Le nom du lieu et l&rsquo;adresse o\u00f9 l&#8217;employ\u00e9 a enregistr\u00e9 la saisie des temps.<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><strong>Auteur et code de l&rsquo;auteur :<\/strong> La personne responsable de la saisie des temps, ainsi que son code d&rsquo;identification.<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><strong>Cr\u00e9\u00e9 le :<\/strong> date et heure auxquelles la saisie des temps a \u00e9t\u00e9 initialement cr\u00e9\u00e9e ou enregistr\u00e9e.<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><strong>Derni\u00e8re modification par et derni\u00e8re modification le :<\/strong> la personne qui a effectu\u00e9 la derni\u00e8re modification de la saisie des temps, ainsi que la date et l&rsquo;heure de la derni\u00e8re modification.<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><strong>R\u00f4le :<\/strong> Le r\u00f4le de la personne responsable de la saisie des temps, comme le propri\u00e9taire, l&rsquo;administrateur, le manager ou le membre.<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><strong>Poste :<\/strong> Le poste occup\u00e9 par l&#8217;employ\u00e9 au sein de l&rsquo;organisation.<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><strong>Selfie pris :<\/strong> Indique si une photo selfie a \u00e9t\u00e9 prise dans le cadre de la saisie des temps.<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><strong>Mode hors ligne :<\/strong> Indique si la saisie des temps a \u00e9t\u00e9 enregistr\u00e9e alors que l&rsquo;appareil \u00e9tait hors ligne.<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><strong>Signal\u00e9 :<\/strong> Indique si la saisie des temps a \u00e9t\u00e9 signal\u00e9e ou marqu\u00e9e pour faire l&rsquo;objet d&rsquo;une attention particuli\u00e8re ou d&rsquo;un examen, par exemple en cas d&rsquo;infraction des pauses ou de non-concordance de la reconnaissance faciale.<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><strong>Fuseau horaire :<\/strong> Le fuseau horaire dans lequel la saisie des temps a \u00e9t\u00e9 enregistr\u00e9e.<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><strong>Sortie automatique du jibble :<\/strong> Indique si la saisie de l&rsquo;heure de sortie a \u00e9t\u00e9 effectu\u00e9e via l&rsquo;enregistrement automatique du syst\u00e8me.<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><strong>Mode application mobile :<\/strong> Indique le mode de l&rsquo;application mobile utilis\u00e9e lors de la saisie des heures, tel que le mode personnel ou le mode kiosque.<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><strong>Nom du planning de travail :<\/strong> Le nom du planning de travail assign\u00e9 \u00e0 l&#8217;employ\u00e9.<\/li>\n<\/ol>\n","protected":false},"author":56,"template":"","meta":{"_acf_changed":false,"footnotes":""},"collections":[1652],"class_list":["post-44673","help","type-help","status-publish","hentry","collections-rapports-et-facturation"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.8 (Yoast SEO v26.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Quels sont les types de rapports pouvant \u00eatre export\u00e9s ?<\/title>\n<meta name=\"description\" content=\"D\u00e9couvrez les diff\u00e9rents types de rapports \u00e0 exporter pour obtenir des informations sur les sch\u00e9mas de temps et de pr\u00e9sence de votre \u00e9quipe.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.jibble.io\/fr\/aide\/quels-sont-les-differents-types-de-rapports-pouvant-etre-exportes\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Quels sont les types de rapports pouvant \u00eatre export\u00e9s ?\" \/>\n<meta property=\"og:description\" content=\"D\u00e9couvrez les diff\u00e9rents types de rapports \u00e0 exporter pour obtenir des informations sur les sch\u00e9mas de temps et de pr\u00e9sence de votre \u00e9quipe.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.jibble.io\/fr\/aide\/quels-sont-les-differents-types-de-rapports-pouvant-etre-exportes\" \/>\n<meta property=\"og:site_name\" content=\"Jibble\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-12T14:20:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.jibble.io\/wp-content\/uploads\/2023\/09\/Exporting-Timesheets-French.png\" \/>\n\t<meta property=\"og:image:width\" content=\"877\" \/>\n\t<meta property=\"og:image:height\" content=\"923\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"11 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.jibble.io\/fr\/aide\/quels-sont-les-differents-types-de-rapports-pouvant-etre-exportes\",\"url\":\"https:\/\/www.jibble.io\/fr\/aide\/quels-sont-les-differents-types-de-rapports-pouvant-etre-exportes\",\"name\":\"Quels sont les types de rapports pouvant \u00eatre export\u00e9s ?\",\"isPartOf\":{\"@id\":\"https:\/\/www.jibble.io\/fr#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.jibble.io\/fr\/aide\/quels-sont-les-differents-types-de-rapports-pouvant-etre-exportes#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.jibble.io\/fr\/aide\/quels-sont-les-differents-types-de-rapports-pouvant-etre-exportes#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.jibble.io\/wp-content\/uploads\/2023\/09\/Exporting-Timesheets-French-730x768.png\",\"datePublished\":\"2023-09-08T02:14:02+00:00\",\"dateModified\":\"2026-04-12T14:20:28+00:00\",\"description\":\"D\u00e9couvrez les diff\u00e9rents types de rapports \u00e0 exporter pour obtenir des informations sur les sch\u00e9mas de temps et de pr\u00e9sence de votre \u00e9quipe.\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.jibble.io\/fr\/aide\/quels-sont-les-differents-types-de-rapports-pouvant-etre-exportes\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.jibble.io\/fr\/aide\/quels-sont-les-differents-types-de-rapports-pouvant-etre-exportes#primaryimage\",\"url\":\"https:\/\/www.jibble.io\/wp-content\/uploads\/2023\/09\/Exporting-Timesheets-French-730x768.png\",\"contentUrl\":\"https:\/\/www.jibble.io\/wp-content\/uploads\/2023\/09\/Exporting-Timesheets-French-730x768.png\"},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.jibble.io\/fr#website\",\"url\":\"https:\/\/www.jibble.io\/fr\",\"name\":\"Jibble\",\"description\":\"Meet the new standard in time tracking software\",\"publisher\":{\"@id\":\"https:\/\/www.jibble.io\/fr#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.jibble.io\/fr?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.jibble.io\/fr#organization\",\"name\":\"Jibble\",\"url\":\"https:\/\/www.jibble.io\/fr\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.jibble.io\/fr#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.jibble.io\/wp-content\/uploads\/2022\/05\/Original-copy-923x1024.png\",\"contentUrl\":\"https:\/\/www.jibble.io\/wp-content\/uploads\/2022\/05\/Original-copy-923x1024.png\",\"width\":\"923\",\"height\":\"1024\",\"caption\":\"Jibble\"},\"image\":{\"@id\":\"https:\/\/www.jibble.io\/fr#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.linkedin.com\/company\/jibble\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Quels sont les types de rapports pouvant \u00eatre export\u00e9s ?","description":"D\u00e9couvrez les diff\u00e9rents types de rapports \u00e0 exporter pour obtenir des informations sur les sch\u00e9mas de temps et de pr\u00e9sence de votre \u00e9quipe.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.jibble.io\/fr\/aide\/quels-sont-les-differents-types-de-rapports-pouvant-etre-exportes","og_locale":"fr_FR","og_type":"article","og_title":"Quels sont les types de rapports pouvant \u00eatre export\u00e9s ?","og_description":"D\u00e9couvrez les diff\u00e9rents types de rapports \u00e0 exporter pour obtenir des informations sur les sch\u00e9mas de temps et de pr\u00e9sence de votre \u00e9quipe.","og_url":"https:\/\/www.jibble.io\/fr\/aide\/quels-sont-les-differents-types-de-rapports-pouvant-etre-exportes","og_site_name":"Jibble","article_modified_time":"2026-04-12T14:20:28+00:00","og_image":[{"width":877,"height":923,"url":"https:\/\/www.jibble.io\/wp-content\/uploads\/2023\/09\/Exporting-Timesheets-French.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"11 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.jibble.io\/fr\/aide\/quels-sont-les-differents-types-de-rapports-pouvant-etre-exportes","url":"https:\/\/www.jibble.io\/fr\/aide\/quels-sont-les-differents-types-de-rapports-pouvant-etre-exportes","name":"Quels sont les types de rapports pouvant \u00eatre export\u00e9s ?","isPartOf":{"@id":"https:\/\/www.jibble.io\/fr#website"},"primaryImageOfPage":{"@id":"https:\/\/www.jibble.io\/fr\/aide\/quels-sont-les-differents-types-de-rapports-pouvant-etre-exportes#primaryimage"},"image":{"@id":"https:\/\/www.jibble.io\/fr\/aide\/quels-sont-les-differents-types-de-rapports-pouvant-etre-exportes#primaryimage"},"thumbnailUrl":"https:\/\/www.jibble.io\/wp-content\/uploads\/2023\/09\/Exporting-Timesheets-French-730x768.png","datePublished":"2023-09-08T02:14:02+00:00","dateModified":"2026-04-12T14:20:28+00:00","description":"D\u00e9couvrez les diff\u00e9rents types de rapports \u00e0 exporter pour obtenir des informations sur les sch\u00e9mas de temps et de pr\u00e9sence de votre \u00e9quipe.","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.jibble.io\/fr\/aide\/quels-sont-les-differents-types-de-rapports-pouvant-etre-exportes"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.jibble.io\/fr\/aide\/quels-sont-les-differents-types-de-rapports-pouvant-etre-exportes#primaryimage","url":"https:\/\/www.jibble.io\/wp-content\/uploads\/2023\/09\/Exporting-Timesheets-French-730x768.png","contentUrl":"https:\/\/www.jibble.io\/wp-content\/uploads\/2023\/09\/Exporting-Timesheets-French-730x768.png"},{"@type":"WebSite","@id":"https:\/\/www.jibble.io\/fr#website","url":"https:\/\/www.jibble.io\/fr","name":"Jibble","description":"Meet the new standard in time tracking software","publisher":{"@id":"https:\/\/www.jibble.io\/fr#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.jibble.io\/fr?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.jibble.io\/fr#organization","name":"Jibble","url":"https:\/\/www.jibble.io\/fr","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.jibble.io\/fr#\/schema\/logo\/image\/","url":"https:\/\/www.jibble.io\/wp-content\/uploads\/2022\/05\/Original-copy-923x1024.png","contentUrl":"https:\/\/www.jibble.io\/wp-content\/uploads\/2022\/05\/Original-copy-923x1024.png","width":"923","height":"1024","caption":"Jibble"},"image":{"@id":"https:\/\/www.jibble.io\/fr#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/jibble\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.jibble.io\/fr\/wp-json\/wp\/v2\/help\/44673","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jibble.io\/fr\/wp-json\/wp\/v2\/help"}],"about":[{"href":"https:\/\/www.jibble.io\/fr\/wp-json\/wp\/v2\/types\/help"}],"author":[{"embeddable":true,"href":"https:\/\/www.jibble.io\/fr\/wp-json\/wp\/v2\/users\/56"}],"version-history":[{"count":3,"href":"https:\/\/www.jibble.io\/fr\/wp-json\/wp\/v2\/help\/44673\/revisions"}],"predecessor-version":[{"id":395374,"href":"https:\/\/www.jibble.io\/fr\/wp-json\/wp\/v2\/help\/44673\/revisions\/395374"}],"wp:attachment":[{"href":"https:\/\/www.jibble.io\/fr\/wp-json\/wp\/v2\/media?parent=44673"}],"wp:term":[{"taxonomy":"collections","embeddable":true,"href":"https:\/\/www.jibble.io\/fr\/wp-json\/wp\/v2\/collections?post=44673"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}